{"id":9698,"date":"2022-08-25T15:18:00","date_gmt":"2022-08-25T13:18:00","guid":{"rendered":"https:\/\/www.asf-fischer.com\/diy-pro-garden\/"},"modified":"2023-06-08T10:40:42","modified_gmt":"2023-06-08T08:40:42","slug":"diy-pro-garden","status":"publish","type":"post","link":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/","title":{"rendered":"DIY Pro &amp; Garden"},"content":{"rendered":"\n<p>Nach l\u00e4ngerer Abwesenheit findet am 5. und 6. September wieder die DIY Pro &amp; Garden Messe statt, die alle zwei Jahre stattfindende Messe f\u00fcr Baumarkt, Fachhandel und Gartencenter.<\/p>\n\n<figure class=\"wp-block-image alignwide size-full\"><img decoding=\"async\" width=\"600\" height=\"265\" src=\"https:\/\/www.asf-fischer.de\/wp-content\/uploads\/2022\/11\/beurs.jpg\" alt=\"\" class=\"wp-image-2233\" srcset=\"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2022\/11\/beurs.jpg 600w, https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2022\/11\/beurs-300x133.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<p>Der Fokus der Fachmesse richtet sich auf den \u201cDo It Yourself\u201d-Fachhandel, dem Baumarkt und den Gartencentern. Die Messe reagiert auf wichtige Trends wie \u201eDo-it-for-me\u201c: Verbraucher die im Fachhandel einkaufen, Profis die im DIY-Handel einkaufen, Handelsformate die sowohl Heimwerker- als auch Profimaterial anbieten. Die DIY Pro &amp; Garden Messe will auf diese Trends reagieren, indem Sie Baum\u00e4rkte, Fachh\u00e4ndler und Gartencenter anspricht mit einem Komplettangebot abgestimmt auf ihre Bed\u00fcrfnisse.  <\/p>\n\n<p><br\/>Wir m\u00f6chten Sie herzlich zu dieser Messe und insbesondere zum ASF Fischer Stand 15 in Halle 1.1 einladen.<br\/>Hier k\u00f6nnen Sie alle unsere (neuen) Artikel im Bereich Au\u00dfenbefestigung und viele weitere Befestigungsprodukte kennenlernen.<\/p>\n\n<p>Wir sind neugierig auf Ihr Unternehmen und Ihre Erfahrungen am Markt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach l\u00e4ngerer Abwesenheit findet am 5. und 6. September wieder die DIY Pro &amp; Garden Messe statt, die alle zwei Jahre stattfindende Messe f\u00fcr Baumarkt, Fachhandel und Gartencenter. Der Fokus der Fachmesse richtet sich auf den \u201cDo It Yourself\u201d-Fachhandel, dem Baumarkt und den Gartencentern. Die Messe reagiert auf wichtige Trends wie \u201eDo-it-for-me\u201c: Verbraucher die im [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[37,6],"tags":[],"class_list":["post-9698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mitarbeitergeschichten","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIY Pro &amp; Garden - A.S.F. Fischer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIY Pro &amp; Garden - A.S.F. Fischer\" \/>\n<meta property=\"og:description\" content=\"Nach l\u00e4ngerer Abwesenheit findet am 5. und 6. September wieder die DIY Pro &amp; Garden Messe statt, die alle zwei Jahre stattfindende Messe f\u00fcr Baumarkt, Fachhandel und Gartencenter. Der Fokus der Fachmesse richtet sich auf den \u201cDo It Yourself\u201d-Fachhandel, dem Baumarkt und den Gartencentern. Die Messe reagiert auf wichtige Trends wie \u201eDo-it-for-me\u201c: Verbraucher die im [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/\" \/>\n<meta property=\"og:site_name\" content=\"A.S.F. Fischer\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-25T13:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-08T08:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asf-fischer.de\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#\\\/schema\\\/person\\\/12e2215d80ad8c1982aba18892cf0f2e\"},\"headline\":\"DIY Pro &amp; Garden\",\"datePublished\":\"2022-08-25T13:18:00+00:00\",\"dateModified\":\"2023-06-08T08:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/\"},\"wordCount\":148,\"publisher\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asf-fischer.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ontwerp-zonder-titel-e1686213690539.jpg\",\"articleSection\":[\"Mitarbeitergeschichten\",\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/\",\"url\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/\",\"name\":\"DIY Pro &amp; Garden - A.S.F. Fischer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asf-fischer.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ontwerp-zonder-titel-e1686213690539.jpg\",\"datePublished\":\"2022-08-25T13:18:00+00:00\",\"dateModified\":\"2023-06-08T08:40:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asf-fischer.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ontwerp-zonder-titel-e1686213690539.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asf-fischer.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Ontwerp-zonder-titel-e1686213690539.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/diy-pro-garden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asf-fischer.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIY Pro &amp; Garden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#website\",\"url\":\"https:\\\/\\\/www.asf-fischer.nl\\\/\",\"name\":\"A.S.F. Fischer\",\"description\":\"Partner in fasteners\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asf-fischer.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#organization\",\"name\":\"A.S.F. Fischer\",\"url\":\"https:\\\/\\\/www.asf-fischer.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asf-fischer.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ASF-Fischer-PIFAT-logo-actueel-e1768991354497-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.asf-fischer.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ASF-Fischer-PIFAT-logo-actueel-e1768991354497-1.svg\",\"caption\":\"A.S.F. Fischer\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asf-fischer.nl\\\/#\\\/schema\\\/person\\\/12e2215d80ad8c1982aba18892cf0f2e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd757a9040831fc3da080fcad7940634964ec760131a27f7908fed6dbc53c0a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd757a9040831fc3da080fcad7940634964ec760131a27f7908fed6dbc53c0a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd757a9040831fc3da080fcad7940634964ec760131a27f7908fed6dbc53c0a5?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/www.asf-fischer.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIY Pro &amp; Garden - A.S.F. Fischer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/","og_locale":"de_DE","og_type":"article","og_title":"DIY Pro &amp; Garden - A.S.F. Fischer","og_description":"Nach l\u00e4ngerer Abwesenheit findet am 5. und 6. September wieder die DIY Pro &amp; Garden Messe statt, die alle zwei Jahre stattfindende Messe f\u00fcr Baumarkt, Fachhandel und Gartencenter. Der Fokus der Fachmesse richtet sich auf den \u201cDo It Yourself\u201d-Fachhandel, dem Baumarkt und den Gartencentern. Die Messe reagiert auf wichtige Trends wie \u201eDo-it-for-me\u201c: Verbraucher die im [&hellip;]","og_url":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/","og_site_name":"A.S.F. Fischer","article_published_time":"2022-08-25T13:18:00+00:00","article_modified_time":"2023-06-08T08:40:42+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.asf-fischer.de\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#article","isPartOf":{"@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/"},"author":{"name":"admin","@id":"https:\/\/www.asf-fischer.nl\/#\/schema\/person\/12e2215d80ad8c1982aba18892cf0f2e"},"headline":"DIY Pro &amp; Garden","datePublished":"2022-08-25T13:18:00+00:00","dateModified":"2023-06-08T08:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/"},"wordCount":148,"publisher":{"@id":"https:\/\/www.asf-fischer.nl\/#organization"},"image":{"@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg","articleSection":["Mitarbeitergeschichten","Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/","url":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/","name":"DIY Pro &amp; Garden - A.S.F. Fischer","isPartOf":{"@id":"https:\/\/www.asf-fischer.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#primaryimage"},"image":{"@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg","datePublished":"2022-08-25T13:18:00+00:00","dateModified":"2023-06-08T08:40:42+00:00","breadcrumb":{"@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#primaryimage","url":"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg","contentUrl":"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.asf-fischer.com\/de\/diy-pro-garden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asf-fischer.com\/de\/"},{"@type":"ListItem","position":2,"name":"DIY Pro &amp; Garden"}]},{"@type":"WebSite","@id":"https:\/\/www.asf-fischer.nl\/#website","url":"https:\/\/www.asf-fischer.nl\/","name":"A.S.F. Fischer","description":"Partner in fasteners","publisher":{"@id":"https:\/\/www.asf-fischer.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asf-fischer.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.asf-fischer.nl\/#organization","name":"A.S.F. Fischer","url":"https:\/\/www.asf-fischer.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asf-fischer.nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2026\/01\/ASF-Fischer-PIFAT-logo-actueel-e1768991354497-1.svg","contentUrl":"https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2026\/01\/ASF-Fischer-PIFAT-logo-actueel-e1768991354497-1.svg","caption":"A.S.F. Fischer"},"image":{"@id":"https:\/\/www.asf-fischer.nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.asf-fischer.nl\/#\/schema\/person\/12e2215d80ad8c1982aba18892cf0f2e","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/cd757a9040831fc3da080fcad7940634964ec760131a27f7908fed6dbc53c0a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd757a9040831fc3da080fcad7940634964ec760131a27f7908fed6dbc53c0a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd757a9040831fc3da080fcad7940634964ec760131a27f7908fed6dbc53c0a5?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/www.asf-fischer.com"]}]}},"uagb_featured_image_src":{"full":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg",1800,1200,false],"thumbnail":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-150x150.jpg",150,150,true],"medium":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-768x512.jpg",768,512,true],"large":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/www.asf-fischer.com\/wp-content\/uploads\/2023\/06\/Ontwerp-zonder-titel-e1686213690539.jpg",1800,1200,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.asf-fischer.com\/de\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Nach l\u00e4ngerer Abwesenheit findet am 5. und 6. September wieder die DIY Pro &amp; Garden Messe statt, die alle zwei Jahre stattfindende Messe f\u00fcr Baumarkt, Fachhandel und Gartencenter. Der Fokus der Fachmesse richtet sich auf den \u201cDo It Yourself\u201d-Fachhandel, dem Baumarkt und den Gartencentern. Die Messe reagiert auf wichtige Trends wie \u201eDo-it-for-me\u201c: Verbraucher die im&hellip;","_links":{"self":[{"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/posts\/9698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/comments?post=9698"}],"version-history":[{"count":1,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/posts\/9698\/revisions"}],"predecessor-version":[{"id":9699,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/posts\/9698\/revisions\/9699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/media\/10665"}],"wp:attachment":[{"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/media?parent=9698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/categories?post=9698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asf-fischer.com\/de\/wp-json\/wp\/v2\/tags?post=9698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}